{"id":22243,"date":"2025-03-05T10:46:57","date_gmt":"2025-03-05T10:46:57","guid":{"rendered":"http:\/\/bookroad.tours\/?post_type=tours&#038;p=22243"},"modified":"2026-02-13T09:47:51","modified_gmt":"2026-02-13T09:47:51","slug":"bodegas-rioja-alavesa","status":"publish","type":"tours","link":"https:\/\/bookroad.tours\/index.php\/tours\/bodegas-rioja-alavesa\/","title":{"rendered":"Tour Bodegas de la Rioja"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Con salida desde Bilbao, San Sebasti\u00e1n o Vitoria-Gasteiz, sum\u00e9rjase en la belleza atemporal de La Rioja, una de las regiones vin\u00edcolas m\u00e1s reconocidas del mundo. Enclavada en el Valle del Ebro y enmarcada por las sierras de Tolo\u00f1o, Cantabria y La Demanda, esta tierra de vi\u00f1edos, pueblos medievales y arraigadas tradiciones vitivin\u00edcolas ofrece una experiencia inolvidable tanto para los amantes del vino como para los amantes de la cultura.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">R<strong>ioja wine tours<\/strong> <strong>Exclusivo con Traslados Privados de Lujo<\/strong>.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Rel\u00e1jese y disfrute de lo mejor de La Rioja mientras nosotros nos encargamos de su transporte, garantizando un viaje impecable y lujoso por esta encantadora regi\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tour bodegas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Este tour es solo una muestra de lo que La Rioja ofrece, una tierra donde el vino, la historia y la cultura se entrelazan. Perm\u00edtanos personalizar su viaje seg\u00fan sus preferencias, ya sea una cata privada, una experiencia gastron\u00f3mica con estrella Michelin o una estancia prolongada en el coraz\u00f3n de la regi\u00f3n vin\u00edcola espa\u00f1ola.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"22556\" src=\"https:\/\/bookroad.tours\/wp-content\/uploads\/2025\/03\/3539285881_5c398175c0_b-1.jpg\" alt=\"\" class=\"wp-image-22556\" srcset=\"https:\/\/bookroad.tours\/wp-content\/uploads\/2025\/03\/3539285881_5c398175c0_b-1.jpg 1024w, https:\/\/bookroad.tours\/wp-content\/uploads\/2025\/03\/3539285881_5c398175c0_b-1-300x225.jpg 300w, https:\/\/bookroad.tours\/wp-content\/uploads\/2025\/03\/3539285881_5c398175c0_b-1-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"22557\" src=\"https:\/\/bookroad.tours\/wp-content\/uploads\/2025\/03\/Recurso-1cabecera-1024x683.jpg\" alt=\"\" class=\"wp-image-22557\" srcset=\"https:\/\/bookroad.tours\/wp-content\/uploads\/2025\/03\/Recurso-1cabecera-1024x683.jpg 1024w, https:\/\/bookroad.tours\/wp-content\/uploads\/2025\/03\/Recurso-1cabecera-300x200.jpg 300w, https:\/\/bookroad.tours\/wp-content\/uploads\/2025\/03\/Recurso-1cabecera-768x513.jpg 768w, https:\/\/bookroad.tours\/wp-content\/uploads\/2025\/03\/Recurso-1cabecera.jpg 1338w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Desde Bilbao, San Sebasti\u00e1n o Vitoria-Gasteiz<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La Rioja es una zona reconocida mundialmente por sus excelentes vinos. Ubicada al norte de Espa\u00f1a, en la cuenca del r\u00edo Ebro y rodeada por las sierras de Tolo\u00f1o, Cantabria y La Demanda, La Rioja nos regala un maravilloso paisaje repleto de vi\u00f1edos y peque\u00f1os pueblos, donde la elaboraci\u00f3n del vino es un arte y una forma de vida para sus habitantes, que lo han transmitido de generaci\u00f3n en generaci\u00f3n. Esta gran combinaci\u00f3n de bellos paisajes, incre\u00edbles bodegas, gastronom\u00eda propia y un rico patrimonio hist\u00f3rico, hace que la visita a La Rioja sea imprescindible para los amantes del vino y su cultura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Te ofrecemos el traslado desde los Aeropuertos cercanos y viajes en coches privados y de lujo, para que t\u00fa solo tengas que preocuparte de disfrutar del buen vino y otras experiencias que La Rioja te trae.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Balc\u00f3n de La Rioja<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La Denominaci\u00f3n de Origen Rioja es un territorio compuesto por varias Comunidades Aut\u00f3nomas (La Rioja, Euskadi y Navarra) y se divide seg\u00fan la climatolog\u00eda propia de cada zona en Rioja Alta, Baja y Rioja Alavesa, causa de las caracter\u00edsticas espec\u00edficas de los diferentes vinos de la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comenzaremos la ruta del vino de Rioja por el balc\u00f3n de la Rioja desde lo alto de la Sierra Cantabria, un mirador que nos permite abarcar con vistas todo el valle del r\u00edo Ebro en esta zona repleta de vi\u00f1edos y bellos pueblos cuyos habitantes viven de la elaboraci\u00f3n de este vino desde tiempos inmemoriales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Elciego<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestra ruta nos lleva ahora a Elciego, otro municipio de Rioja Alavesa, que nos sorprende ya desde la distancia gracias al famoso edificio de las Bodegas Marqu\u00e9s de Riscal, un hotel dise\u00f1ado por Frank Gehry. El edificio destaca entre las casas tradicionales de piedra de la zona, creando una sensaci\u00f3n de irrealidad, que pronto nos sacude al entrar en el pueblo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Ciudad del Vino de Marqu\u00e9s de Riscal es un claro ejemplo de lo que es el vino y la cultura en esta zona. Adem\u00e1s de las antiguas bodegas de mediados del siglo XIX, el complejo incluye un hotel de lujo, un spa especializado en vinos y dos prestigiosos restaurantes que har\u00e1n las delicias de los visitantes. Pero Elciego tambi\u00e9n nos ofrece su cara m\u00e1s tradicional, la que encontramos recorriendo sus calles y que nos ofrece un paseo por sus alrededores, caminando entre vi\u00f1edos mostr\u00e1ndonos una imagen diferente seg\u00fan la estaci\u00f3n del a\u00f1o en la que nos encontremos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Laguardia<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Laguardia es la parada imprescindible en nuestro recorrido por estas tierras de vi\u00f1edos. Situado sobre un cerro, este pueblo amurallado se divisa desde lejos, como invit\u00e1ndonos a visitarlo y a conocer su historia y sus gentes. Lo primero que llama la atenci\u00f3n de esta villa es su muralla, vestigio de su antigua funci\u00f3n como plaza fuerte que defend\u00eda los l\u00edmites del antiguo Reino de Navarra. Una vez pasamos una de las cinco puertas de acceso y ya dentro del recinto amurallado, nos encontramos con un entorno que recuerda al medievo: calles estrechas con casas, iglesias y palacios realizados con la piedra siller\u00eda t\u00edpica de la zona. Pero Laguardia tiene una parte oculta, ya que hay un pueblo subterr\u00e1neo que mucha gente desconoce: se trata de las bodegas familiares o \u201ccuevas\u201d que llevan siglos excavadas en el subsuelo. Estas bodegas, tambi\u00e9n habituales en otros pueblos del entorno, nos dan testimonio de la importancia del vino en la econom\u00eda de la zona desde tiempos inmemoriales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Rioja Alavesa<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El entorno del pueblo de Laguardia tambi\u00e9n es espectacular. Podemos comprobarlo desde el Paseo del Collado. A las vistas sobre la majestuosa Sierra de Cantabria que domina la zona norte del Valle, hay que sumar los vi\u00f1edos que se extienden hasta donde alcanza la vista. La silueta de las Bodegas Ysios justo debajo del paseo es realmente impresionante. Y no nos olvidemos de los Lagos de Laguardia, un entorno natural protegido que se encuentra al Este del pueblo y que encierra riquezas naturales de gran valor ecol\u00f3gico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y aqu\u00ed ponemos punto y final a esta ruta que s\u00f3lo pretende ser una peque\u00f1a muestra de todo lo que la tierra de La Rioja puede ofrecer a los amantes del vino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La combinaci\u00f3n perfecta de bellos paisajes, incre\u00edbles bodegas, gastronom\u00eda propia y un rico patrimonio hist\u00f3rico.<\/p>\n","protected":false},"featured_media":21831,"menu_order":0,"template":"","meta":{"_acf_changed":false},"categories":[],"tags":[],"region":[69],"tour-type":[119],"class_list":["post-22243","tours","type-tours","status-publish","has-post-thumbnail","hentry","region-paisvasco","tour-type-tour-enologico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tour Bodegas de la Rioja - Bookroad Tours<\/title>\n<meta name=\"description\" content=\"Descubre las prestigiosas bodegas de La Rioja en un tour privado con chofer. Disfruta de catas exclusivas y alojamientos de lujo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bookroad.tours\/index.php\/tours\/bodegas-rioja-alavesa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour Bodegas de la Rioja - Bookroad Tours\" \/>\n<meta property=\"og:description\" content=\"Descubre las prestigiosas bodegas de La Rioja en un tour privado con chofer. Disfruta de catas exclusivas y alojamientos de lujo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bookroad.tours\/index.php\/tours\/bodegas-rioja-alavesa\/\" \/>\n<meta property=\"og:site_name\" content=\"Bookroad Tours\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-13T09:47:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bookroad.tours\/wp-content\/uploads\/2025\/02\/Elciego-Spain-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1476\" \/>\n\t<meta property=\"og:image:height\" content=\"986\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bookroad.tours\\\/index.php\\\/tours\\\/bodegas-rioja-alavesa\\\/\",\"url\":\"https:\\\/\\\/bookroad.tours\\\/index.php\\\/tours\\\/bodegas-rioja-alavesa\\\/\",\"name\":\"Tour Bodegas de la Rioja - Bookroad Tours\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bookroad.tours\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bookroad.tours\\\/index.php\\\/tours\\\/bodegas-rioja-alavesa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bookroad.tours\\\/index.php\\\/tours\\\/bodegas-rioja-alavesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bookroad.tours\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Elciego-Spain-2.jpg\",\"datePublished\":\"2025-03-05T10:46:57+00:00\",\"dateModified\":\"2026-02-13T09:47:51+00:00\",\"description\":\"Descubre las prestigiosas bodegas de La Rioja en un tour privado con chofer. Disfruta de catas exclusivas y alojamientos de lujo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bookroad.tours\\\/index.php\\\/tours\\\/bodegas-rioja-alavesa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bookroad.tours\\\/index.php\\\/tours\\\/bodegas-rioja-alavesa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bookroad.tours\\\/index.php\\\/tours\\\/bodegas-rioja-alavesa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bookroad.tours\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Elciego-Spain-2.jpg\",\"contentUrl\":\"https:\\\/\\\/bookroad.tours\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Elciego-Spain-2.jpg\",\"width\":1476,\"height\":986},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bookroad.tours\\\/index.php\\\/tours\\\/bodegas-rioja-alavesa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bookroad.tours\\\/index.php\\\/en\\\/main\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tours\",\"item\":\"https:\\\/\\\/bookroad.tours\\\/index.php\\\/tours\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tour Bodegas de la Rioja\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bookroad.tours\\\/#website\",\"url\":\"https:\\\/\\\/bookroad.tours\\\/\",\"name\":\"Bookroad Tours\",\"description\":\"Your Spain Luxury Travel Experts\",\"publisher\":{\"@id\":\"https:\\\/\\\/bookroad.tours\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bookroad.tours\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bookroad.tours\\\/#organization\",\"name\":\"Bookroad Tours\",\"url\":\"https:\\\/\\\/bookroad.tours\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bookroad.tours\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bookroad.tours\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-logo-br-tours2-3.png\",\"contentUrl\":\"https:\\\/\\\/bookroad.tours\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-logo-br-tours2-3.png\",\"width\":1084,\"height\":233,\"caption\":\"Bookroad Tours\"},\"image\":{\"@id\":\"https:\\\/\\\/bookroad.tours\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tour Bodegas de la Rioja - Bookroad Tours","description":"Descubre las prestigiosas bodegas de La Rioja en un tour privado con chofer. Disfruta de catas exclusivas y alojamientos de lujo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bookroad.tours\/index.php\/tours\/bodegas-rioja-alavesa\/","og_locale":"es_ES","og_type":"article","og_title":"Tour Bodegas de la Rioja - Bookroad Tours","og_description":"Descubre las prestigiosas bodegas de La Rioja en un tour privado con chofer. Disfruta de catas exclusivas y alojamientos de lujo.","og_url":"https:\/\/bookroad.tours\/index.php\/tours\/bodegas-rioja-alavesa\/","og_site_name":"Bookroad Tours","article_modified_time":"2026-02-13T09:47:51+00:00","og_image":[{"width":1476,"height":986,"url":"https:\/\/bookroad.tours\/wp-content\/uploads\/2025\/02\/Elciego-Spain-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bookroad.tours\/index.php\/tours\/bodegas-rioja-alavesa\/","url":"https:\/\/bookroad.tours\/index.php\/tours\/bodegas-rioja-alavesa\/","name":"Tour Bodegas de la Rioja - Bookroad Tours","isPartOf":{"@id":"https:\/\/bookroad.tours\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bookroad.tours\/index.php\/tours\/bodegas-rioja-alavesa\/#primaryimage"},"image":{"@id":"https:\/\/bookroad.tours\/index.php\/tours\/bodegas-rioja-alavesa\/#primaryimage"},"thumbnailUrl":"https:\/\/bookroad.tours\/wp-content\/uploads\/2025\/02\/Elciego-Spain-2.jpg","datePublished":"2025-03-05T10:46:57+00:00","dateModified":"2026-02-13T09:47:51+00:00","description":"Descubre las prestigiosas bodegas de La Rioja en un tour privado con chofer. Disfruta de catas exclusivas y alojamientos de lujo.","breadcrumb":{"@id":"https:\/\/bookroad.tours\/index.php\/tours\/bodegas-rioja-alavesa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bookroad.tours\/index.php\/tours\/bodegas-rioja-alavesa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bookroad.tours\/index.php\/tours\/bodegas-rioja-alavesa\/#primaryimage","url":"https:\/\/bookroad.tours\/wp-content\/uploads\/2025\/02\/Elciego-Spain-2.jpg","contentUrl":"https:\/\/bookroad.tours\/wp-content\/uploads\/2025\/02\/Elciego-Spain-2.jpg","width":1476,"height":986},{"@type":"BreadcrumbList","@id":"https:\/\/bookroad.tours\/index.php\/tours\/bodegas-rioja-alavesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bookroad.tours\/index.php\/en\/main\/"},{"@type":"ListItem","position":2,"name":"Tours","item":"https:\/\/bookroad.tours\/index.php\/tours\/"},{"@type":"ListItem","position":3,"name":"Tour Bodegas de la Rioja"}]},{"@type":"WebSite","@id":"https:\/\/bookroad.tours\/#website","url":"https:\/\/bookroad.tours\/","name":"Bookroad Tours","description":"Your Spain Luxury Travel Experts","publisher":{"@id":"https:\/\/bookroad.tours\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bookroad.tours\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/bookroad.tours\/#organization","name":"Bookroad Tours","url":"https:\/\/bookroad.tours\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bookroad.tours\/#\/schema\/logo\/image\/","url":"https:\/\/bookroad.tours\/wp-content\/uploads\/2025\/02\/cropped-logo-br-tours2-3.png","contentUrl":"https:\/\/bookroad.tours\/wp-content\/uploads\/2025\/02\/cropped-logo-br-tours2-3.png","width":1084,"height":233,"caption":"Bookroad Tours"},"image":{"@id":"https:\/\/bookroad.tours\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bookroad.tours\/index.php\/wp-json\/wp\/v2\/tours\/22243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bookroad.tours\/index.php\/wp-json\/wp\/v2\/tours"}],"about":[{"href":"https:\/\/bookroad.tours\/index.php\/wp-json\/wp\/v2\/types\/tours"}],"version-history":[{"count":8,"href":"https:\/\/bookroad.tours\/index.php\/wp-json\/wp\/v2\/tours\/22243\/revisions"}],"predecessor-version":[{"id":24639,"href":"https:\/\/bookroad.tours\/index.php\/wp-json\/wp\/v2\/tours\/22243\/revisions\/24639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bookroad.tours\/index.php\/wp-json\/wp\/v2\/media\/21831"}],"wp:attachment":[{"href":"https:\/\/bookroad.tours\/index.php\/wp-json\/wp\/v2\/media?parent=22243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bookroad.tours\/index.php\/wp-json\/wp\/v2\/categories?post=22243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bookroad.tours\/index.php\/wp-json\/wp\/v2\/tags?post=22243"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/bookroad.tours\/index.php\/wp-json\/wp\/v2\/region?post=22243"},{"taxonomy":"tour-type","embeddable":true,"href":"https:\/\/bookroad.tours\/index.php\/wp-json\/wp\/v2\/tour-type?post=22243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}